

{"id":18060,"date":"2018-11-27T16:32:04","date_gmt":"2018-11-27T15:32:04","guid":{"rendered":"https:\/\/fundaciojoseppla.cat\/tienda\/publicaciones-de-josep-pla\/"},"modified":"2023-10-30T12:36:43","modified_gmt":"2023-10-30T11:36:43","slug":"publicaciones-sobre-josep-pla-2","status":"publish","type":"page","link":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/","title":{"rendered":"Publicaciones sobre Josep Pla"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18060\" class=\"elementor elementor-18060 elementor-17601\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6900d91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6900d91\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a1ffd0c\" data-id=\"6a1ffd0c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17820b05 elementor-widget elementor-widget-image\" data-id=\"17820b05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"714\" height=\"1024\" src=\"https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla-714x1024.jpg\" class=\"attachment-large size-large wp-image-15999\" alt=\"\" srcset=\"https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla-714x1024.jpg 714w, https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla-209x300.jpg 209w, https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla-768x1102.jpg 768w, https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla.jpg 1300w\" sizes=\"(max-width: 714px) 100vw, 714px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40b57aba elementor-widget elementor-widget-text-editor\" data-id=\"40b57aba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Foto Enric Bruguera<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-71ecf84d\" data-id=\"71ecf84d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59257886 claredonlight elementor-widget elementor-widget-heading\" data-id=\"59257886\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tienda<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78279ba8 elementor-widget elementor-widget-spacer\" data-id=\"78279ba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65d63abd claredonregular elementor-widget elementor-widget-button\" data-id=\"65d63abd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/fundaciojoseppla.cat\/es\/tienda\/libros-de-josep-pla\/#seccio46\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Libros de Josep Pla<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-626b9cde claredonregular elementor-widget elementor-widget-button\" data-id=\"626b9cde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla\/#seccio47\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Publicaciones sobre Josep Pla<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f28652 claredonregular elementor-widget elementor-widget-button\" data-id=\"f28652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/fundaciojoseppla.cat\/es\/tienda\/puntos-de-libro\/#seccio48\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Puntos de libro<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b73813c claredonregular elementor-widget elementor-widget-button\" data-id=\"4b73813c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/fundaciojoseppla.cat\/es\/tienda\/materiales-de-papeleria-y-recuerdos\/#seccio49\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Materiales de papeleria y recuerdos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28ba01e0 claredonregular elementor-widget elementor-widget-button\" data-id=\"28ba01e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/fundaciojoseppla.cat\/es\/tienda\/videos-cds-y-dvds\/#seccio50\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Videos, CD's y DVD's<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3da298e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3da298e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75fe902\" data-id=\"75fe902\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a5527c elementor-widget elementor-widget-menu-anchor\" data-id=\"1a5527c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"seccio47\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87880e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87880e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e06b78b\" data-id=\"e06b78b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce991f9 claredonlight elementor-widget elementor-widget-heading\" data-id=\"ce991f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Publicaciones de Josep Pla y otros<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e114368 elementor-widget elementor-widget-text-editor\" data-id=\"e114368\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gatell, Cristina i Soler, Gl\u00f2ria. <strong><em>Amb el corrent de proa.<\/em><\/strong>\u00a0Quaderns Crema, Barcelona, 2012. <strong>29,50 \u20ac<\/strong><\/p><p>Ferran, \u00c0ngel. <strong><em>Big Jack, El Sanguinari<\/em><\/strong>. Ed. A Contravent, Barcelona, 2008. <strong>15,00 \u20ac<\/strong><\/p><p>Gran\u00e9s, Joan. <strong><em>El mirall inhum\u00e0<\/em><\/strong>. Ed. A Contravent, Barcelona, 2010. <strong>18,50 \u20ac<\/strong><\/p><p>Pericay, Xavier. <strong><em>Josep Pla y el viejo periodismo<\/em><\/strong>. Destino, Barcelona, 2009. <strong>20,00 \u20ac<\/strong><\/p><p>Pi, Flori\u00e0. <strong><em>La cuina d\u2019en Florian i na Maruja<\/em><\/strong>. Palafrugell, 2015. <strong>15,00 \u20ac<\/strong><\/p><p>Pla, Xavier. Josep Pla. <strong><em>Ficci\u00f3 autobiogr\u00e0fica i veritat liter\u00e0ria<\/em><\/strong>. Quaderns Crema, Barcelona,\u00a0 1997. <strong>21,50 \u20ac<\/strong><\/p><p>Xargay, Xavier. <strong><em>Escriptors a Palafrugell<\/em><\/strong>. Quaderns de Palafrugell, Ajuntament de Palafrugell, Diputaci\u00f3 de Girona. Palafrugell, 1999. <strong>17,00 \u20ac<\/strong><\/p><p><strong><em><br \/>Carpeta Ruta Josep Pla<\/em><\/strong>. <strong>6,00 \u20ac<\/strong><\/p><p>AADD. <strong><em>Literatura, territori i identitat<\/em><\/strong>. La gesti\u00f3 del patrimoni literari a debat, Espais escrits. <strong>17,00 \u20ac<\/strong><\/p><p>Aliu, Joan (gui\u00f3 i dibuixos). <em><strong>Notes de Josep Pla en c\u00f2mic.\u00a0<\/strong><\/em>Ed. Baix Empord\u00e0, 1997. <strong>13,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg de l&#8217;exposici\u00f3 <strong><em>&#8220;El primer artista que vaig con\u00e8ixer&#8221;. Joan B. Coromina i Josep Pla<\/em><\/strong>, 2019. <strong>14,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg de l\u2019exposici\u00f3 <strong><em>Professors de solitud. J. Esquirol, fot\u00f2graf \u2013 J. Pla, escriptor<\/em><\/strong>, 2018. <strong>2,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg de l\u2019exposici\u00f3 <strong><em>Mig Europa cau. Impressions de Josep Pla sobre la Gran Guerra<\/em><\/strong>, 2017. <strong>20,00 \u20ac<\/strong><\/p><p>\u00c0lbum de records <strong><em>Josep Pla i la civilitzaci\u00f3 surera<\/em><\/strong>, 2016. <strong>30,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>Notes sobre Par\u00eds<\/em><\/strong>, 2014. <strong>20,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>A l&#8217;ombra de Josep Pla. Cinc escriptors-periodistes gironins de la Rep\u00fablica<\/em><\/strong> 2011. <strong>18,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>Jaume Vicens Vives &#8211; Josep Pla. Complicitats<\/em><\/strong>, 2010. <strong>15,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>Pla, l&#8217;Herm\u00f3s i companyia<\/em><\/strong>, 2008. <strong>&#8212;<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>Pels camins de l&#8217;Empord\u00e0. G\u00fcnter Grass-Josep Pla<\/em><\/strong>, 2008. <strong>12,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>Pla, bi\u00f2graf de Rusi\u00f1ol<\/em><\/strong> , 2007. <strong>&#8212;<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>Josep Pla i els pintors. La construcci\u00f3 del paisatge empordan\u00e8s<\/em><\/strong>,\u00a0 2006. <strong>&#8212;<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>Josep Pla. Cartes d&#8217;It\u00e0lia<\/em><\/strong>, 2005. <strong>10,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>Salvador Dal\u00ed, Josep Pla. Coincid\u00e8ncies<\/em><\/strong>, 2004. <strong>10,00 \u20ac<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>El temps que fuig<\/em><\/strong>, 2003. <strong>10,00 \u20ac<\/strong><\/p><p><strong><em>Gaud\u00ed i Verdaguer Llegits per Josep Pla<\/em><\/strong>. Anna Aguil\u00f3 i Xavier Pla (eds.). Diversitas, 51, Universitat de Girona, 2006. <strong>12,00 \u20ac<\/strong><\/p><p><strong><em>El carrer Estret. La po\u00e8tica de la banalitat<\/em><\/strong>. Jornada d\u2019estudi, 2001. <strong>&#8212;<\/strong><\/p><p>Cat\u00e0leg exposici\u00f3 <strong><em>Josep Pla. La diab\u00f2lica mania d\u2019escriure<\/em><\/strong>, 1997. <strong>&#8212;<\/strong><\/p><p><strong><em>Josep Pla. Mem\u00f2ria i escriptura<\/em><\/strong>. Actes del Col\u00b7loqui de l\u2019Any Pla, 1997. <strong>12,00 \u20ac<\/strong><\/p><p><strong><em>Mem\u00f2ria Any Pla<\/em> 1997<\/strong>. <strong>&#8212;<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8e635a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8e635a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-452c394b\" data-id=\"452c394b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-743e528d elementor-skin-carousel elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"743e528d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;4&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositivas\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0010_Layer-23\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0010_Layer-23.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0011_Layer-22\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0011_Layer-22.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0012_Layer-20\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0012_Layer-20.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0013_Layer-21\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0013_Layer-21.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0014_Layer-19\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0014_Layer-19.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0015_Layer-18\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0015_Layer-18.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0016_Layer-17\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0016_Layer-17.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0017_Layer-16\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0017_Layer-16.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0018_Layer-15\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0018_Layer-15.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0020_Layer-13\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0020_Layer-13.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions_0024_Layer-9\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions_0024_Layer-9.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions-151\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions-151.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"publicacions-152\" style=\"background-image: url(&#039;https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/11\/publicacions-152.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Siguiente\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Foto Enric Bruguera Tienda Libros de Josep Pla Publicaciones sobre Josep Pla Puntos de libro Materiales de papeleria y recuerdos Videos, CD&#8217;s y DVD&#8217;s Publicaciones de Josep Pla y otros Gatell, Cristina i Soler, Gl\u00f2ria. Amb el corrent de proa.\u00a0Quaderns Crema, Barcelona, 2012. 29,50 \u20ac Ferran, \u00c0ngel. Big Jack, El Sanguinari. Ed. A Contravent, Barcelona, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":7284,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"disabled","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-18060","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Publicaciones sobre Josep Pla - Fundaci\u00f3 Josep Pla<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Publicaciones sobre Josep Pla - Fundaci\u00f3 Josep Pla\" \/>\n<meta property=\"og:description\" content=\"Foto Enric Bruguera Tienda Libros de Josep Pla Publicaciones sobre Josep Pla Puntos de libro Materiales de papeleria y recuerdos Videos, CD&#8217;s y DVD&#8217;s Publicaciones de Josep Pla y otros Gatell, Cristina i Soler, Gl\u00f2ria. Amb el corrent de proa.\u00a0Quaderns Crema, Barcelona, 2012. 29,50 \u20ac Ferran, \u00c0ngel. Big Jack, El Sanguinari. Ed. A Contravent, Barcelona, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3 Josep Pla\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FJosepPla\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T11:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla-714x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@FJosepPla\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/tienda\\\/publicaciones-sobre-josep-pla-2\\\/\",\"url\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/tienda\\\/publicaciones-sobre-josep-pla-2\\\/\",\"name\":\"Publicaciones sobre Josep Pla - Fundaci\u00f3 Josep Pla\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/tienda\\\/publicaciones-sobre-josep-pla-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/tienda\\\/publicaciones-sobre-josep-pla-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/botiga-fundacio-josep-pla-714x1024.jpg\",\"datePublished\":\"2018-11-27T15:32:04+00:00\",\"dateModified\":\"2023-10-30T11:36:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/tienda\\\/publicaciones-sobre-josep-pla-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/tienda\\\/publicaciones-sobre-josep-pla-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/tienda\\\/publicaciones-sobre-josep-pla-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/botiga-fundacio-josep-pla-714x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/botiga-fundacio-josep-pla-714x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/tienda\\\/publicaciones-sobre-josep-pla-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Publicaciones sobre Josep Pla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/\",\"name\":\"Fundaci\u00f3 Josep Pla\",\"description\":\"Fundacio Josep Pla Palafrugell\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/#organization\",\"name\":\"Fundaci\u00f3 Josep Pla\",\"url\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/negre-transparent-de-logo-vecto-FJP.png\",\"contentUrl\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/negre-transparent-de-logo-vecto-FJP.png\",\"width\":600,\"height\":233,\"caption\":\"Fundaci\u00f3 Josep Pla\"},\"image\":{\"@id\":\"https:\\\/\\\/fundaciojoseppla.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FJosepPla\\\/\",\"https:\\\/\\\/x.com\\\/FJosepPla\",\"http:\\\/\\\/pinterest.com\\\/fjoseppla\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FJosepPla\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Publicaciones sobre Josep Pla - Fundaci\u00f3 Josep Pla","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/","og_locale":"es_ES","og_type":"article","og_title":"Publicaciones sobre Josep Pla - Fundaci\u00f3 Josep Pla","og_description":"Foto Enric Bruguera Tienda Libros de Josep Pla Publicaciones sobre Josep Pla Puntos de libro Materiales de papeleria y recuerdos Videos, CD&#8217;s y DVD&#8217;s Publicaciones de Josep Pla y otros Gatell, Cristina i Soler, Gl\u00f2ria. Amb el corrent de proa.\u00a0Quaderns Crema, Barcelona, 2012. 29,50 \u20ac Ferran, \u00c0ngel. Big Jack, El Sanguinari. Ed. A Contravent, Barcelona, [&hellip;]","og_url":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/","og_site_name":"Fundaci\u00f3 Josep Pla","article_publisher":"https:\/\/www.facebook.com\/FJosepPla\/","article_modified_time":"2023-10-30T11:36:43+00:00","og_image":[{"url":"https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla-714x1024.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@FJosepPla","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/","url":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/","name":"Publicaciones sobre Josep Pla - Fundaci\u00f3 Josep Pla","isPartOf":{"@id":"https:\/\/fundaciojoseppla.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/#primaryimage"},"image":{"@id":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/#primaryimage"},"thumbnailUrl":"https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla-714x1024.jpg","datePublished":"2018-11-27T15:32:04+00:00","dateModified":"2023-10-30T11:36:43+00:00","breadcrumb":{"@id":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/#primaryimage","url":"https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla-714x1024.jpg","contentUrl":"https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/08\/botiga-fundacio-josep-pla-714x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/publicaciones-sobre-josep-pla-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/fundaciojoseppla.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/fundaciojoseppla.cat\/es\/tienda\/"},{"@type":"ListItem","position":3,"name":"Publicaciones sobre Josep Pla"}]},{"@type":"WebSite","@id":"https:\/\/fundaciojoseppla.cat\/es\/#website","url":"https:\/\/fundaciojoseppla.cat\/es\/","name":"Fundaci\u00f3 Josep Pla","description":"Fundacio Josep Pla Palafrugell","publisher":{"@id":"https:\/\/fundaciojoseppla.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundaciojoseppla.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fundaciojoseppla.cat\/es\/#organization","name":"Fundaci\u00f3 Josep Pla","url":"https:\/\/fundaciojoseppla.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fundaciojoseppla.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/05\/negre-transparent-de-logo-vecto-FJP.png","contentUrl":"https:\/\/fundaciojoseppla.cat\/wp-content\/uploads\/2018\/05\/negre-transparent-de-logo-vecto-FJP.png","width":600,"height":233,"caption":"Fundaci\u00f3 Josep Pla"},"image":{"@id":"https:\/\/fundaciojoseppla.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FJosepPla\/","https:\/\/x.com\/FJosepPla","http:\/\/pinterest.com\/fjoseppla\/","https:\/\/www.youtube.com\/user\/FJosepPla"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:25:50","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/fundaciojoseppla.cat\/es\/wp-json\/wp\/v2\/pages\/18060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundaciojoseppla.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fundaciojoseppla.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fundaciojoseppla.cat\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fundaciojoseppla.cat\/es\/wp-json\/wp\/v2\/comments?post=18060"}],"version-history":[{"count":11,"href":"https:\/\/fundaciojoseppla.cat\/es\/wp-json\/wp\/v2\/pages\/18060\/revisions"}],"predecessor-version":[{"id":38799,"href":"https:\/\/fundaciojoseppla.cat\/es\/wp-json\/wp\/v2\/pages\/18060\/revisions\/38799"}],"up":[{"embeddable":true,"href":"https:\/\/fundaciojoseppla.cat\/es\/wp-json\/wp\/v2\/pages\/7284"}],"wp:attachment":[{"href":"https:\/\/fundaciojoseppla.cat\/es\/wp-json\/wp\/v2\/media?parent=18060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}